{"id":6467,"date":"2024-01-09T16:18:56","date_gmt":"2024-01-09T16:18:56","guid":{"rendered":"https:\/\/www.sarix.com\/sarix-opportunita-di-lavoro\/"},"modified":"2024-01-10T07:30:02","modified_gmt":"2024-01-10T07:30:02","slug":"sarix-opportunita-di-lavoro","status":"publish","type":"page","link":"https:\/\/www.sarix.com\/it\/contatto\/sarix-opportunita-di-lavoro\/","title":{"rendered":"SARIX OPPORTUNIT\u00c0 DI LAVORO"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6467\" class=\"elementor elementor-6467 elementor-6436\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00ca7b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00ca7b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-768104e\" data-id=\"768104e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf16829 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cf16829\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.sarix.com\/it\/sarix-abbraccia-lindustria-4-0-interattiva-e-connessa\/\"><font color=\"#878787\"><span style=\"font-size: 18.72px\"><b>SCOPRI LE OPPORTUNIT\u00c0 DI LAVORO DI SARI<\/b><\/span><\/font><span style=\"font-weight: bold\">X&nbsp;<\/span><span style=\"font-weight: bold\"><br><\/span><br><\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1d2568 elementor-widget elementor-widget-text-editor\" data-id=\"d1d2568\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" style=\"font-family: Roboto, sans-serif; color: var( --e-global-color-primary ); line-height: 20px; font-weight: 400; text-align: center;\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\"><span style=\"color: #878787;\"><span style=\"font-weight: bold;\">Sarix offre un ambiente di lavoro di prima classe nei settori tecnologici in espansione. <\/span><\/span><\/h3>\n<h3 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" style=\"font-family: Roboto, sans-serif; color: var( --e-global-color-primary ); line-height: 20px; font-weight: 400; text-align: center;\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\"><span style=\"color: #878787;\"><span style=\"font-weight: bold;\">Orientata a livello globale ma gestibile, le dimensioni dell&#8217;azienda offrono la combinazione perfetta per <\/span><\/span><\/h3>\n<h3 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" style=\"font-family: Roboto, sans-serif; color: var( --e-global-color-primary ); line-height: 20px; font-weight: 400; text-align: center;\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\"><span style=\"color: #878787;\"><span style=\"font-weight: bold;\">Orientati alla crescita, persone che agiscono, personalit\u00e0 disposte a fare la differenza.<\/span><\/span><\/h3>\n<h3 data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\"> <\/h3>\n<h3 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" style=\"font-family: Roboto, sans-serif; color: var( --e-global-color-primary ); line-height: 20px; font-weight: 400; text-align: center;\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\"><span style=\"color: #878787;\"><span style=\"font-weight: bold;\">Visualizza l&#8217;opportunit\u00e0 di lavoro.  <\/span><\/span><\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c16820e\" data-id=\"c16820e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af4df86 elementor-widget elementor-widget-spacer\" data-id=\"af4df86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-258856f elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"258856f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4774c3c\" data-id=\"4774c3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c69f51 elementor-widget__width-initial fluent-form-widget-step-header-yes fluent-form-widget-step-progressbar-yes fluentform-widget-submit-button-custom elementor-widget elementor-widget-fluent-form-widget\" data-id=\"6c69f51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"fluent-form-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"fluentform-widget-wrapper fluentform-widget-align-default\">\n\n            \n            <div class='fluentform ff-default fluentform_wrapper_13 ffs_custom_wrap'><form data-form_id=\"13\" id=\"fluentform_13\" class=\"frm-fluent-form fluent_form_13 ff-el-form-top ff_form_instance_13_1 ff-form-loading ffs_custom\" data-form_instance=\"ff_form_instance_13_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Job Application Form SARIX<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='6467' \/><input type=\"hidden\" id=\"_fluentform_13_fluentformnonce\" name=\"_fluentform_13_fluentformnonce\" value=\"25daeee5ac\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/it\/wp-json\/wp\/v2\/pages\/6467\" \/><div class='ff-el-group  ff-custom_html' tabindex='-1' data-name=\"custom_html-13_1\" ><hr \/>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center\"><span style=\"color: #3366ff\"><strong><a style=\"color: #3366ff\" href=\"https:\/\/www.sarix.com\/sdc_download\/6544\/?key=4hwo2jx0ejuwa7jni9zhixnqocyili\">Sales engineer for high precision machine tools<\/a><\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center\"><span style=\"color: #3366ff\"><a style=\"color: #3366ff\" href=\"https:\/\/www.sarix.com\/sdc_download\/6559\/?key=rluag9gwpg7krzl7x7bhe3pu4qhh4i\">Service and customer training technician<\/a><\/span><\/h2>\n<hr \/><\/div><div class='ff-el-group  ff-custom_html' tabindex='-1' data-name=\"custom_html-13_2\" ><h3 style=\"text-align: center\">__________ Job Application Form ___________<\/h3>\n<p style=\"text-align: center\">Please fill out the form below to submit your job application!<\/p>\n<p style=\"text-align: center\">Compila il modulo sottostante per inviare la tua candidatura per un lavoro!<\/p>\n<hr \/><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_dropdown_1' id='label_ff_13_dropdown_1' aria-label=\"Applied position \/ Posizione applicata\">Applied position \/ Posizione applicata<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown_1\" id=\"ff_13_dropdown_1\" class=\"ff-el-form-control\" data-name=\"dropdown_1\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_13_dropdown_1\"><option value=\"\">Select position \/  Seleziona la posizione<\/option><option value=\"Service and customer training technician\"  >Service and customer training technician<\/option><option value=\"Sales engineer for high precision machine tools\"  >Sales engineer for high precision machine tools<\/option><\/select><\/div><\/div><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group  ff-el-form-top'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_13_names_first_name_' id='label_ff_13_names_first_name_' >First Name \/ Nome<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_13_names_first_name_\" class=\"ff-el-form-control\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group  ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_names_last_name_' id='label_ff_13_names_last_name_' >Last Name \/ Cognome<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_13_names_last_name_\" class=\"ff-el-form-control\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_email' id='label_ff_13_email' aria-label=\"Email Address\">Email Address<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_13_email\" class=\"ff-el-form-control\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_phone' id='label_ff_13_phone' aria-label=\"Phone\/Mobile\">Phone\/Mobile<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone ff_el_with_extended_validation\" type=\"tel\" placeholder=\"Mobile Number\" data-name=\"phone\" id=\"ff_13_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=true><\/div><\/div><\/div><\/div><div class=\"ff-name-address-wrapper fluent-address\" data-type=\"address-element\" data-name=\"address_1\" ><div class='ff-el-input--label'><label aria-label=\"Present Address\">Present Address<\/label><\/div><div class='ff-el-input--content'><div class='ff-t-container'><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_address_1_address_line_1_' id='label_ff_13_address_1_address_line_1_' aria-label=\"Address Line 1\">Address Line 1<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"address_1[address_line_1]\" id=\"ff_13_address_1_address_line_1_\" class=\"ff-el-form-control\" data-key_name=\"address_line_1\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_address_1_city_' id='label_ff_13_address_1_city_' aria-label=\"City\">City<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"address_1[city]\" id=\"ff_13_address_1_city_\" class=\"ff-el-form-control\" data-key_name=\"city\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><div class='ff-t-container'><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_address_1_zip_' id='label_ff_13_address_1_zip_' aria-label=\"Zip Code\">Zip Code<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"address_1[zip]\" id=\"ff_13_address_1_zip_\" class=\"ff-el-form-control\" data-key_name=\"zip\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_address_1_country_' id='label_ff_13_address_1_country_' aria-label=\"Country\">Country<\/label><\/div><div class='ff-el-input--content'><select name=\"address_1[country]\" id=\"ff_13_address_1_country_\" class=\"ff-el-form-control\" data-key_name=\"country\" aria-invalid='false' aria-required=true><option value=''><\/option><option value='AF' >Afganistan<\/option><option value='AL' >Albania<\/option><option value='DZ' >Algeria<\/option><option value='AD' >Andorra<\/option><option value='AO' >Angola<\/option><option value='AI' >Anguilla<\/option><option value='AQ' >Antartide<\/option><option value='AG' >Antigua e Barbuda<\/option><option value='SA' >Arabia Saudita<\/option><option value='AR' >Argentina<\/option><option value='AM' >Armenia<\/option><option value='AW' >Aruba<\/option><option value='AU' >Australia<\/option><option value='AT' >Austria<\/option><option value='AZ' >Azerbaigian<\/option><option value='BS' >Bahamas<\/option><option value='BH' >Bahrein<\/option><option value='BD' >Bangladesh<\/option><option value='BB' >Barbados<\/option><option value='BE' >Belgio<\/option><option value='BZ' >Belize<\/option><option value='BJ' >Benin<\/option><option value='BM' >Bermuda<\/option><option value='BY' >Bielorussia<\/option><option value='MM' >Birmania<\/option><option value='BO' >Bolivia<\/option><option value='BQ' >Bonaire, Sant&#039;Eustazio e Saba<\/option><option value='BA' >Bosnia ed Erzegovina<\/option><option value='BW' >Botswana<\/option><option value='BR' >Brasile<\/option><option value='BN' >Brunei<\/option><option value='BG' >Bulgaria<\/option><option value='BF' >Burkina Faso<\/option><option value='BI' >Burundi<\/option><option value='KH' >Cambogia<\/option><option value='CM' >Camerun<\/option><option value='CA' >Canada<\/option><option value='CV' >Capo Verde<\/option><option value='TD' >Chad<\/option><option value='CL' >Chile<\/option><option value='CN' >Cina<\/option><option value='CY' >Cipro<\/option><option value='CO' >Colombia<\/option><option value='KM' >Comore<\/option><option value='KR' >Corea del Sud<\/option><option value='KP' >Corea del nord<\/option><option value='CR' >Costa Rica<\/option><option value='CI' >Costa d&#039;Avorio<\/option><option value='HR' >Croazia<\/option><option value='CU' >Cuba<\/option><option value='CW' >Cura\u00e7ao<\/option><option value='DK' >Danimarca<\/option><option value='EC' >Ecuador<\/option><option value='EG' >Egitto<\/option><option value='SV' >El Salvador<\/option><option value='AE' >Emirati Arabi Uniti<\/option><option value='ER' >Eritrea<\/option><option value='EE' >Estonia<\/option><option value='SZ' >Eswatini<\/option><option value='ET' >Etiopia<\/option><option value='FJ' >Figi<\/option><option value='PH' >Filippine<\/option><option value='FI' >Finlandia<\/option><option value='FR' >Francia<\/option><option value='GA' >Gabon<\/option><option value='GM' >Gambia<\/option><option value='GE' >Georgia<\/option><option value='GS' >Georgia del Sud\/Isole Sandwich<\/option><option value='DE' >Germania<\/option><option value='GH' >Ghana<\/option><option value='JM' >Giamaica<\/option><option value='JP' >Giappone<\/option><option value='GI' >Gibilterra<\/option><option value='DJ' >Gibuti<\/option><option value='JO' >Giordania<\/option><option value='GR' >Grecia<\/option><option value='GD' >Grenada<\/option><option value='GL' >Groenlandia<\/option><option value='GP' >Guadalupa<\/option><option value='GU' >Guam<\/option><option value='GT' >Guatemala<\/option><option value='GG' >Guernsey<\/option><option value='GN' >Guinea<\/option><option value='GW' >Guinea Bissau<\/option><option value='GQ' >Guinea Equatoriale<\/option><option value='GY' >Guyana<\/option><option value='GF' >Guyana francese<\/option><option value='HT' >Haiti<\/option><option value='HN' >Honduras<\/option><option value='HK' >Hong Kong<\/option><option value='BT' >Il Bhutan<\/option><option value='PY' >Il Paraguay<\/option><option value='IN' >India<\/option><option value='ID' >Indonesia<\/option><option value='IQ' >Iraq<\/option><option value='IE' >Irlanda<\/option><option value='IS' >Islanda<\/option><option value='BV' >Isola Bouvet<\/option><option value='NF' >Isola Norfolk<\/option><option value='IM' >Isola di Man<\/option><option value='CX' >Isola di Natale<\/option><option value='KY' >Isole Cayman<\/option><option value='CC' >Isole Cocos (Keeling)<\/option><option value='CK' >Isole Cook<\/option><option value='FK' >Isole Falkland<\/option><option value='FO' >Isole Faroe<\/option><option value='HM' >Isole Heard e McDonald<\/option><option value='MP' >Isole Marianne Settentrionali<\/option><option value='MH' >Isole Marshall<\/option><option value='SB' >Isole Salomone<\/option><option value='TC' >Isole Turks e Caicos<\/option><option value='VG' >Isole Vergini Britanniche<\/option><option value='VI' >Isole Vergini americane (USA)<\/option><option value='UM' >Isole minori esterne degli Stati Uniti (USA)<\/option><option value='AX' >Isole \u00c5land<\/option><option value='IL' >Israele<\/option><option value='IT' >Italia<\/option><option value='KZ' >Kazakistan<\/option><option value='KE' >Kenia<\/option><option value='KG' >Kirghizistan<\/option><option value='KI' >Kiribati<\/option><option value='XK' >Kosovo<\/option><option value='KW' >Kuwait<\/option><option value='IR' >L&#039;Iran<\/option><option value='NA' >La Namibia<\/option><option value='DM' >La dominica<\/option><option value='LA' >Laos<\/option><option value='SC' >Le Seychelles<\/option><option value='LS' >Lesoto<\/option><option value='LV' >Lettonia<\/option><option value='LB' >Libano<\/option><option value='LR' >Liberia<\/option><option value='LY' >Libia<\/option><option value='LI' >Liechtenstein<\/option><option value='LT' >Lituania<\/option><option value='LU' >Lussemburgo<\/option><option value='MO' >Macao S.A.R., Cina<\/option><option value='MK' >Macedonia<\/option><option value='MG' >Madagascar<\/option><option value='JE' >Maglia<\/option><option value='YT' >Majotte<\/option><option value='MW' >Malawi<\/option><option value='MY' >Malaysia<\/option><option value='MV' >Maldive<\/option><option value='ML' >Mali<\/option><option value='MT' >Malta<\/option><option value='MA' >Marocco<\/option><option value='MQ' >Martinica<\/option><option value='MR' >Mauritania<\/option><option value='MU' >Maurizio<\/option><option value='MX' >Messico<\/option><option value='FM' >Micronesia<\/option><option value='MD' >Moldavia<\/option><option value='MC' >Monaco<\/option><option value='MN' >Mongolia<\/option><option value='ME' >Montenegro<\/option><option value='MS' >Montserrat<\/option><option value='MZ' >Mozambico<\/option><option value='NR' >Nauru<\/option><option value='NP' >Nepal<\/option><option value='NI' >Nicaragua<\/option><option value='NE' >Niger<\/option><option value='NG' >Nigeria<\/option><option value='NU' >Niue<\/option><option value='NO' >Norvegia<\/option><option value='NC' >Nuova Caledonia<\/option><option value='NZ' >Nuova Zelanda<\/option><option value='OM' >Oman<\/option><option value='NL' >Paesi Bassi<\/option><option value='PK' >Pakistan<\/option><option value='PW' >Palau<\/option><option value='PA' >Panama<\/option><option value='PG' >Papua Nuova Guinea<\/option><option value='PE' >Per\u00f9<\/option><option value='PN' >Pitcairn<\/option><option value='PF' >Polinesia francese<\/option><option value='PL' >Polonia<\/option><option value='PT' >Portogallo<\/option><option value='PR' >Portorico<\/option><option value='QA' >Qatar<\/option><option value='GB' >Regno Unito (UK)<\/option><option value='CZ' >Repubblica Ceca<\/option><option value='CF' >Repubblica Centrafricana<\/option><option value='CD' >Repubblica Democratica del Congo (Kinshasa)<\/option><option value='DO' >Repubblica Dominicana<\/option><option value='CG' >Repubblica del Congo (Brazzaville)<\/option><option value='RE' >Riunione<\/option><option value='RO' >Romania<\/option><option value='RW' >Ruanda<\/option><option value='RU' >Russia<\/option><option value='EH' >Sahara Occidentale<\/option><option value='KN' >Saint Kitts e Nevis<\/option><option value='MF' >Saint Martin (parte francese)<\/option><option value='SX' >Saint Martin (parte olandese)<\/option><option value='PM' >Saint Pierre e Miquelon<\/option><option value='VC' >Saint Vincent e Grenadine<\/option><option value='BL' >Saint-Barth\u00e9lemy<\/option><option value='WS' >Samoa<\/option><option value='AS' >Samoa americane<\/option><option value='SM' >San Marino<\/option><option value='SH' >Sant&#039;Elena<\/option><option value='LC' >Santa Lucia<\/option><option value='ST' >Sao Tome e Principe<\/option><option value='SN' >Senegal<\/option><option value='RS' >Serbia<\/option><option value='SL' >Sierra Leone<\/option><option value='SG' >Singapore<\/option><option value='SY' >Siria<\/option><option value='SK' >Slovacchia<\/option><option value='SI' >Slovenia<\/option><option value='SO' >Somalia<\/option><option value='ES' >Spagna<\/option><option value='LK' >Sri Lanka<\/option><option value='US' >Stati Uniti (USA)<\/option><option value='ZA' >Sudafrica<\/option><option value='SD' >Sudan<\/option><option value='SS' >Sudan del Sud<\/option><option value='SR' >Suriname<\/option><option value='SJ' >Svalbard e Jan Mayen<\/option><option value='SE' >Svezia<\/option><option value='CH' >Svizzera<\/option><option value='TJ' >Tagikistan<\/option><option value='TW' >Taiwan<\/option><option value='TZ' >Tanzania<\/option><option value='TF' >Territori francesi australi<\/option><option value='IO' >Territorio britannico dell&#039;Oceano Indiano<\/option><option value='PS' >Territorio palestinese<\/option><option value='TH' >Thailandia<\/option><option value='TL' >Timor Est<\/option><option value='TG' >Togo<\/option><option value='TK' >Tokelau<\/option><option value='TO' >Tonga<\/option><option value='TT' >Trinidad e Tobago<\/option><option value='TN' >Tunisia<\/option><option value='TM' >Turkmenistan<\/option><option value='TV' >Tuvalu<\/option><option value='TR' >T\u00fcrkiye<\/option><option value='UA' >Ucraina<\/option><option value='UG' >Uganda<\/option><option value='HU' >Ungheria<\/option><option value='UY' >Uruguay<\/option><option value='UZ' >Uzbekistan<\/option><option value='VU' >Vanuatu<\/option><option value='VA' >Vaticano<\/option><option value='VE' >Venezuela<\/option><option value='VN' >Vietnam<\/option><option value='WF' >Wallis e Futuna<\/option><option value='YE' >Yemen<\/option><option value='ZM' >Zambia<\/option><option value='ZW' >Zimbabwe<\/option><\/select><\/div><\/div><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_2\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_description_3' id='label_ff_13_description_3' aria-label=\"Cover Letter \/ Lettera di presentazione\">Cover Letter \/ Lettera di presentazione<\/label><div class=\"ff-el-tooltip\" data-content=\"Please do not exceed 300 words.\"><svg viewbox=\"0 0 25 25\"><path d=\"m329 393l0-46c0-2-1-4-2-6-2-2-4-3-7-3l-27 0 0-146c0-3-1-5-3-7-2-1-4-2-7-2l-91 0c-3 0-5 1-7 2-1 2-2 4-2 7l0 46c0 2 1 5 2 6 2 2 4 3 7 3l27 0 0 91-27 0c-3 0-5 1-7 3-1 2-2 4-2 6l0 46c0 3 1 5 2 7 2 1 4 2 7 2l128 0c3 0 5-1 7-2 1-2 2-4 2-7z m-36-256l0-46c0-2-1-4-3-6-2-2-4-3-7-3l-54 0c-3 0-5 1-7 3-2 2-3 4-3 6l0 46c0 3 1 5 3 7 2 1 4 2 7 2l54 0c3 0 5-1 7-2 2-2 3-4 3-7z m182 119c0 40-9 77-29 110-20 34-46 60-80 80-33 20-70 29-110 29-40 0-77-9-110-29-34-20-60-46-80-80-20-33-29-70-29-110 0-40 9-77 29-110 20-34 46-60 80-80 33-20 70-29 110-29 40 0 77 9 110 29 34 20 60 46 80 80 20 33 29 70 29 110z\"><\/path><\/svg><\/div><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_13_description_3\" name=\"description_3\" id=\"ff_13_description_3\" class=\"ff-el-form-control\" rows=\"5\" cols=\"2\" maxlength=\"2000\" data-name=\"description_3\" ><\/textarea><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_datetime_1' id='label_ff_13_datetime_1' aria-label=\"Earliest Possible Start Date \/ Prima data di inizio possibile\">Earliest Possible Start Date \/ Prima data di inizio possibile<\/label><\/div><div class='ff-el-input--content'><input  aria-label='Earliest Possible Start Date \/ Prima data di inizio possibile Use arrow keys to navigate dates. Press enter to select a date.'  aria-haspopup='dialog' data-type-datepicker data-format='d\/m\/Y' type=\"text\" name=\"datetime_1\" id=\"ff_13_datetime_1\" class=\"ff-el-form-control ff-el-datepicker\" data-name=\"datetime_1\"  aria-invalid='false' aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_file-upload_1' id='label_ff_13_file-upload_1' aria-label=\"Upload Your Resume \/ Carica il tuo curriculum\">Upload Your Resume \/ Carica il tuo curriculum<\/label><\/div><div class='ff-el-input--content'><label for='ff_13_file-upload_1' class='ff_file_upload_holder'><span class='ff_upload_btn ff-btn' tabindex='0'>Choose File<\/span> <input type=\"file\" name=\"file-upload\" id=\"ff_13_file-upload_1\" class=\"ff-el-form-control  ff-screen-reader-element\" data-name=\"file-upload\" multiple=\"1\"  aria-invalid='false' aria-required=true><\/label><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_13_description' id='label_ff_13_description' aria-label=\"Additional Information \/ Informazioni aggiuntive\">Additional Information \/ Informazioni aggiuntive<\/label><div class=\"ff-el-tooltip\" data-content=\"If Applicable\"><svg viewbox=\"0 0 25 25\"><path d=\"m329 393l0-46c0-2-1-4-2-6-2-2-4-3-7-3l-27 0 0-146c0-3-1-5-3-7-2-1-4-2-7-2l-91 0c-3 0-5 1-7 2-1 2-2 4-2 7l0 46c0 2 1 5 2 6 2 2 4 3 7 3l27 0 0 91-27 0c-3 0-5 1-7 3-1 2-2 4-2 6l0 46c0 3 1 5 2 7 2 1 4 2 7 2l128 0c3 0 5-1 7-2 1-2 2-4 2-7z m-36-256l0-46c0-2-1-4-3-6-2-2-4-3-7-3l-54 0c-3 0-5 1-7 3-2 2-3 4-3 6l0 46c0 3 1 5 3 7 2 1 4 2 7 2l54 0c3 0 5-1 7-2 2-2 3-4 3-7z m182 119c0 40-9 77-29 110-20 34-46 60-80 80-33 20-70 29-110 29-40 0-77-9-110-29-34-20-60-46-80-80-20-33-29-70-29-110 0-40 9-77 29-110 20-34 46-60 80-80 33-20 70-29 110-29 40 0 77 9 110 29 34 20 60 46 80 80 20 33 29 70 29 110z\"><\/path><\/svg><\/div><\/div><div class='ff-el-input--content'><textarea aria-required=\"false\" aria-labelledby=\"label_ff_13_description\" name=\"description\" id=\"ff_13_description\" class=\"ff-el-form-control\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\"  aria-label=\"Apply\">Apply<\/button><\/div><\/fieldset><\/form><div id='fluentform_13_errors' class='ff-errors-in-stack ff_form_instance_13_1 ff-form-loading_errors ff_form_instance_13_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_13_1 = {\"id\":\"13\",\"ajaxUrl\":\"https:\\\/\\\/www.sarix.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_13_1\",\"form_id_selector\":\"fluentform_13\",\"rules\":{\"dropdown_1\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"names[first_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[last_name]\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global\":false,\"global_message\":\"This field must contain a valid email\"}},\"phone\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"},\"valid_phone_number\":{\"value\":true,\"message\":\"Phone number is not valid\",\"global\":false,\"global_message\":\"Phone number is not valid\"}},\"address_1[address_line_1]\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"address_1[address_line_2]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"address_1[city]\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"address_1[state]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"address_1[zip]\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"address_1[country]\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"description_3\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"datetime_1\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"file-upload\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"},\"max_file_size\":{\"value\":1048576,\"_valueFrom\":\"MB\",\"message\":\"Maximum file size limit is 1MB\",\"global\":false,\"global_message\":\"Validation fails for maximum file size\"},\"max_file_count\":{\"value\":1,\"message\":\"You can upload maximum 1 file\",\"global\":false,\"global_message\":\"Validation fails for maximum file count\"},\"allowed_file_types\":{\"value\":[\"jpg|jpeg|gif|png|bmp\",\"pdf\",\"doc|ppt|pps|xls|mdb|docx|xlsx|pptx|odt|odp|ods|odg|odc|odb|odf|rtf|txt\"],\"message\":\"Invalid file type\",\"global\":false,\"global_message\":\"Invalid file type\"}},\"description\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}}},\"debounce_time\":300,\"file_upload_settings\":[]};\n                            <\/script>\n                        <\/div>\n\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4d6db8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4d6db8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e5fa30\" data-id=\"4e5fa30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SCOPRI LE OPPORTUNIT\u00c0 DI LAVORO DI SARIX&nbsp; Sarix offre un ambiente di lavoro di prima classe nei settori tecnologici in espansione. Orientata a livello globale ma gestibile, le dimensioni dell&#8217;azienda offrono la combinazione perfetta per Orientati alla crescita, persone che agiscono, personalit\u00e0 disposte a fare la differenza. Visualizza l&#8217;opportunit\u00e0 di lavoro. Job Application Form SARIX [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":6570,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_angie_page":false,"footnotes":""},"categories":[15,3],"tags":[],"class_list":["post-6467","page","type-page","status-publish","hentry","category-contact-form","category-sarix-content"],"_links":{"self":[{"href":"https:\/\/www.sarix.com\/it\/wp-json\/wp\/v2\/pages\/6467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sarix.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sarix.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sarix.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sarix.com\/it\/wp-json\/wp\/v2\/comments?post=6467"}],"version-history":[{"count":11,"href":"https:\/\/www.sarix.com\/it\/wp-json\/wp\/v2\/pages\/6467\/revisions"}],"predecessor-version":[{"id":6753,"href":"https:\/\/www.sarix.com\/it\/wp-json\/wp\/v2\/pages\/6467\/revisions\/6753"}],"up":[{"embeddable":true,"href":"https:\/\/www.sarix.com\/it\/wp-json\/wp\/v2\/pages\/6570"}],"wp:attachment":[{"href":"https:\/\/www.sarix.com\/it\/wp-json\/wp\/v2\/media?parent=6467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sarix.com\/it\/wp-json\/wp\/v2\/categories?post=6467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sarix.com\/it\/wp-json\/wp\/v2\/tags?post=6467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}